{"id":196,"date":"2024-03-20T22:57:37","date_gmt":"2024-03-20T22:57:37","guid":{"rendered":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/"},"modified":"2024-03-20T22:57:37","modified_gmt":"2024-03-20T22:57:37","slug":"machine-gun-kelly-camila-cabello-bad-things-official-music-video","status":"publish","type":"post","link":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/","title":{"rendered":"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)"},"content":{"rendered":"<p>Machine Gun Kelly&#8217;s new album &#8216;bloom&#8217; is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Machine Gun Kelly&#8217;s new album &#8216;bloom&#8217; is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: &#8230;<\/p>\n","protected":false},"author":1,"featured_media":217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[10],"tags":[1064,1080,1053,1039,1008,1095,1104,1086,1025,644,1071],"actors":[],"class_list":["post-196","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-pop-music","tag-bad","tag-boy","tag-cabello","tag-camila","tag-gun","tag-hip","tag-hop","tag-interscope","tag-kelly","tag-machine","tag-things","post_format-post-format-video"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Machine Gun Kelly&#039;s new album &#039;bloom&#039; is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: ...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"opbook\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"TWiT Videos - LGBTQIA+ YouTube Videos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Machine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video) - TWiT Videos\" \/>\n\t\t<meta property=\"og:description\" content=\"Machine Gun Kelly&#039;s new album &#039;bloom&#039; is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: ...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-20T22:57:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-20T22:57:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheRealTwitMagazine\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@twtmagazine\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Machine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video) - TWiT Videos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Machine Gun Kelly&#039;s new album &#039;bloom&#039; is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: ...\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@twtmagazine\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#blogposting\",\"name\":\"Machine Gun Kelly, Camila Cabello \\u2013 Bad Things (Official Music Video) - TWiT Videos\",\"headline\":\"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)\",\"author\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/author\\\/opbook\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video.jpg\",\"width\":480,\"height\":360},\"datePublished\":\"2024-03-20T22:57:37-05:00\",\"dateModified\":\"2024-03-20T22:57:37-05:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#webpage\"},\"articleSection\":\"Pop Music, Bad, Boy, Cabello, Camila, Gun, Hip, Hop, Interscope, Kelly, Machine, Things, Video\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/twitvideos.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/#listItem\",\"name\":\"Music Videos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/#listItem\",\"position\":2,\"name\":\"Music Videos\",\"item\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/pop-music\\\/#listItem\",\"name\":\"Pop Music\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/pop-music\\\/#listItem\",\"position\":3,\"name\":\"Pop Music\",\"item\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/pop-music\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#listItem\",\"name\":\"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/#listItem\",\"name\":\"Music Videos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#listItem\",\"position\":4,\"name\":\"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/category\\\/music-videos\\\/pop-music\\\/#listItem\",\"name\":\"Pop Music\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/#organization\",\"name\":\"TWiT Videos\",\"description\":\"LGBTQIA+ YouTube Videos\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/\",\"telephone\":\"+17137794366\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/TwitVideosLogo.png\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#organizationLogo\",\"width\":262,\"height\":140,\"caption\":\"Twit Videos Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TheRealTwitMagazine\",\"https:\\\/\\\/twitter.com\\\/twtmagazine\",\"https:\\\/\\\/www.instagram.com\\\/steve.pardue\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/SteveLPardue\\\/\",\"https:\\\/\\\/studio.youtube.com\\\/channel\\\/UC_C2oRczgZOMajsdQOuhvcQ\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/stpardue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/author\\\/opbook\\\/#author\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/author\\\/opbook\\\/\",\"name\":\"opbook\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#authorImage\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1714386f7d0401a8462168b0026f6337.jpg?ver=1783509682\",\"width\":96,\"height\":96,\"caption\":\"opbook\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#webpage\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/\",\"name\":\"Machine Gun Kelly, Camila Cabello \\u2013 Bad Things (Official Music Video) - TWiT Videos\",\"description\":\"Machine Gun Kelly's new album 'bloom' is available now! http:\\\/\\\/smarturl.it\\\/MGKbloom Follow MGK: ...\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/author\\\/opbook\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/author\\\/opbook\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video.jpg\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#mainImage\",\"width\":480,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/index.php\\\/2024\\\/03\\\/20\\\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\\\/#mainImage\"},\"datePublished\":\"2024-03-20T22:57:37-05:00\",\"dateModified\":\"2024-03-20T22:57:37-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/twitvideos.com\\\/#website\",\"url\":\"https:\\\/\\\/twitvideos.com\\\/\",\"name\":\"TWiT Videos\",\"description\":\"LGBTQIA+ YouTube Videos\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/twitvideos.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Machine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video) - TWiT Videos","description":"Machine Gun Kelly's new album 'bloom' is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: ...","canonical_url":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#blogposting","name":"Machine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video) - TWiT Videos","headline":"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)","author":{"@id":"https:\/\/twitvideos.com\/index.php\/author\/opbook\/#author"},"publisher":{"@id":"https:\/\/twitvideos.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/twitvideos.com\/wp-content\/uploads\/2024\/03\/machine-gun-kelly-camila-cabello-bad-things-official-music-video.jpg","width":480,"height":360},"datePublished":"2024-03-20T22:57:37-05:00","dateModified":"2024-03-20T22:57:37-05:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#webpage"},"isPartOf":{"@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#webpage"},"articleSection":"Pop Music, Bad, Boy, Cabello, Camila, Gun, Hip, Hop, Interscope, Kelly, Machine, Things, Video"},{"@type":"BreadcrumbList","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/twitvideos.com#listItem","position":1,"name":"Home","item":"https:\/\/twitvideos.com","nextItem":{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/#listItem","name":"Music Videos"}},{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/#listItem","position":2,"name":"Music Videos","item":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/pop-music\/#listItem","name":"Pop Music"},"previousItem":{"@type":"ListItem","@id":"https:\/\/twitvideos.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/pop-music\/#listItem","position":3,"name":"Pop Music","item":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/pop-music\/","nextItem":{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#listItem","name":"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/#listItem","name":"Music Videos"}},{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#listItem","position":4,"name":"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)","previousItem":{"@type":"ListItem","@id":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/pop-music\/#listItem","name":"Pop Music"}}]},{"@type":"Organization","@id":"https:\/\/twitvideos.com\/#organization","name":"TWiT Videos","description":"LGBTQIA+ YouTube Videos","url":"https:\/\/twitvideos.com\/","telephone":"+17137794366","logo":{"@type":"ImageObject","url":"https:\/\/twitvideos.com\/wp-content\/uploads\/2024\/03\/TwitVideosLogo.png","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#organizationLogo","width":262,"height":140,"caption":"Twit Videos Logo"},"image":{"@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/TheRealTwitMagazine","https:\/\/twitter.com\/twtmagazine","https:\/\/www.instagram.com\/steve.pardue\/","https:\/\/www.pinterest.com\/SteveLPardue\/","https:\/\/studio.youtube.com\/channel\/UC_C2oRczgZOMajsdQOuhvcQ","https:\/\/www.linkedin.com\/in\/stpardue"]},{"@type":"Person","@id":"https:\/\/twitvideos.com\/index.php\/author\/opbook\/#author","url":"https:\/\/twitvideos.com\/index.php\/author\/opbook\/","name":"opbook","image":{"@type":"ImageObject","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#authorImage","url":"https:\/\/twitvideos.com\/wp-content\/litespeed\/avatar\/1714386f7d0401a8462168b0026f6337.jpg?ver=1783509682","width":96,"height":96,"caption":"opbook"}},{"@type":"WebPage","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#webpage","url":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/","name":"Machine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video) - TWiT Videos","description":"Machine Gun Kelly's new album 'bloom' is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: ...","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/twitvideos.com\/#website"},"breadcrumb":{"@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#breadcrumblist"},"author":{"@id":"https:\/\/twitvideos.com\/index.php\/author\/opbook\/#author"},"creator":{"@id":"https:\/\/twitvideos.com\/index.php\/author\/opbook\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/twitvideos.com\/wp-content\/uploads\/2024\/03\/machine-gun-kelly-camila-cabello-bad-things-official-music-video.jpg","@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#mainImage","width":480,"height":360},"primaryImageOfPage":{"@id":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/#mainImage"},"datePublished":"2024-03-20T22:57:37-05:00","dateModified":"2024-03-20T22:57:37-05:00"},{"@type":"WebSite","@id":"https:\/\/twitvideos.com\/#website","url":"https:\/\/twitvideos.com\/","name":"TWiT Videos","description":"LGBTQIA+ YouTube Videos","inLanguage":"en-US","publisher":{"@id":"https:\/\/twitvideos.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"TWiT Videos - LGBTQIA+ YouTube Videos","og:type":"article","og:title":"Machine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video) - TWiT Videos","og:description":"Machine Gun Kelly's new album 'bloom' is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: ...","og:url":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/","article:published_time":"2024-03-20T22:57:37+00:00","article:modified_time":"2024-03-20T22:57:37+00:00","article:publisher":"https:\/\/www.facebook.com\/TheRealTwitMagazine","twitter:card":"summary_large_image","twitter:site":"@twtmagazine","twitter:title":"Machine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video) - TWiT Videos","twitter:description":"Machine Gun Kelly's new album 'bloom' is available now! http:\/\/smarturl.it\/MGKbloom Follow MGK: ...","twitter:creator":"@twtmagazine"},"aioseo_meta_data":{"post_id":"196","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-07 00:01:38","updated":"2025-06-03 22:38:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/twitvideos.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/\" title=\"Music Videos\">Music Videos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/pop-music\/\" title=\"Pop Music\">Pop Music<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMachine Gun Kelly, Camila Cabello \u2013 Bad Things (Official Music Video)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/twitvideos.com"},{"label":"Music Videos","link":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/"},{"label":"Pop Music","link":"https:\/\/twitvideos.com\/index.php\/category\/music-videos\/pop-music\/"},{"label":"Machine Gun Kelly, Camila Cabello &#8211; Bad Things (Official Music Video)","link":"https:\/\/twitvideos.com\/index.php\/2024\/03\/20\/machine-gun-kelly-camila-cabello-bad-things-official-music-video\/"}],"_links":{"self":[{"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/posts\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":0,"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/posts\/196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/media\/217"}],"wp:attachment":[{"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/categories?post=196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/tags?post=196"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/twitvideos.com\/index.php\/wp-json\/wp\/v2\/actors?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}